{"id":520,"date":"2025-12-04T09:05:45","date_gmt":"2025-12-04T09:05:45","guid":{"rendered":"https:\/\/bergidyll.sebazzo.com\/rooms\/large-double-room\/"},"modified":"2025-12-10T23:38:21","modified_gmt":"2025-12-10T23:38:21","slug":"large-double-room","status":"publish","type":"page","link":"https:\/\/bergidyll.sebazzo.com\/en\/rooms\/large-double-room\/","title":{"rendered":"Large Double Room"},"content":{"rendered":"\n\t<section class=\"section slider-landing\" id=\"section_1374695939\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-263720740\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1738481540\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-2734198704\" class=\"text\">\n\t\t\n<h1 style=\"font-size: 60px;\">Large Double Room<\/h1>\n\t\t\n<style>\n#text-2734198704 {\n  color: rgb(40, 40, 40);\n}\n#text-2734198704 > * {\n  color: rgb(40, 40, 40);\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1738481540 {\n  width: 60%;\n}\n#text-box-1738481540 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-263720740 {\n  padding-top: 318px;\n  background-color: rgb(247, 239, 222);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1374695939 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_1374695939 .section-bg-overlay {\n  background-color: rgba(61, 36, 36, 0.5);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_541786540\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-307883304\">\n\n\t<div id=\"col-1367072920\" class=\"col medium-5 small-12 large-5\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1081624300\" class=\"text\">\n\t\t\n<p style=\"font-size: 20px;  \">Bergidyll Andermatt.<\/p>\n<h2 style=\"font-size: 50px; line-height:55px; margin-top: -20px;\">More space. More vibe. More you.<\/h2>\n\t\t\n<style>\n#text-1081624300 {\n  color: rgb(0, 0, 0);\n}\n#text-1081624300 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-412895739\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1679435226\" class=\"text\">\n\t\t\n<p style=\"font-size: 25px;\">For longer stays or extra comfort. With king bed, some with balcony or terrace \u2013 ideal for those who need space for themselves (and good dreams).<\/p>\n\t\t\n<style>\n#text-1679435226 {\n  color: rgb(0,0,0);\n}\n#text-1679435226 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_541786540 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 239, 222);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1066383986\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large align-middle\"  id=\"row-517555392\">\n\n\t<div id=\"col-1316798413\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"font-size: 40px;  \">Amenities.<\/p>\n\n<div style=\"color:#000000; font-family:Arial, sans-serif; letter-spacing:2px; font-size:18px; line-height:1.6; width:100%;\">\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n 18\u201326 M\u00b2 \u2013 TIMELESS ALPINE WITH MODERN ACCENTS\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n PRIVATE BATHROOM WITH SHOWER\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n KING BED\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n CARPETED FLOOR\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n TV-FREE\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n WLAN\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n SOME WITH BALCONY OR TERRACE\n    <\/div>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-812517355\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-1366419457\" >\n    <div class=\"slider slider-nav-dots-dashes-spaced slider-nav-circle slider-nav-large slider-nav-dark slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_515962962\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/918cc632-d21b-4eda-9f98-b0e000d07a42-1024x576.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/918cc632-d21b-4eda-9f98-b0e000d07a42-1024x576.jpeg 1024w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/918cc632-d21b-4eda-9f98-b0e000d07a42-300x169.jpeg 300w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/918cc632-d21b-4eda-9f98-b0e000d07a42-768x432.jpeg 768w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/918cc632-d21b-4eda-9f98-b0e000d07a42-1536x864.jpeg 1536w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/918cc632-d21b-4eda-9f98-b0e000d07a42.jpeg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_515962962 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_658317144\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/cb549677-1a6e-49be-9d5e-b0e000d08740-1-1024x576.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/cb549677-1a6e-49be-9d5e-b0e000d08740-1-1024x576.jpeg 1024w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/cb549677-1a6e-49be-9d5e-b0e000d08740-1-300x169.jpeg 300w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/cb549677-1a6e-49be-9d5e-b0e000d08740-1-768x432.jpeg 768w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/cb549677-1a6e-49be-9d5e-b0e000d08740-1-1536x864.jpeg 1536w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/cb549677-1a6e-49be-9d5e-b0e000d08740-1.jpeg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_658317144 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1937185899\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/a91ba160-e72c-4c2f-9c7d-b0e000d09579-1-1024x576.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/a91ba160-e72c-4c2f-9c7d-b0e000d09579-1-1024x576.jpeg 1024w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/a91ba160-e72c-4c2f-9c7d-b0e000d09579-1-300x169.jpeg 300w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/a91ba160-e72c-4c2f-9c7d-b0e000d09579-1-768x432.jpeg 768w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/a91ba160-e72c-4c2f-9c7d-b0e000d09579-1-1536x864.jpeg 1536w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/a91ba160-e72c-4c2f-9c7d-b0e000d09579-1.jpeg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1937185899 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1407284284\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/758d61f5-fc8b-4bc8-b162-b0e000d0c654-1-1024x576.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/758d61f5-fc8b-4bc8-b162-b0e000d0c654-1-1024x576.jpeg 1024w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/758d61f5-fc8b-4bc8-b162-b0e000d0c654-1-300x169.jpeg 300w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/758d61f5-fc8b-4bc8-b162-b0e000d0c654-1-768x432.jpeg 768w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/758d61f5-fc8b-4bc8-b162-b0e000d0c654-1-1536x864.jpeg 1536w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/758d61f5-fc8b-4bc8-b162-b0e000d0c654-1.jpeg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1407284284 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-812517355 > .col-inner {\n  margin: 0px 0px -29px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1066383986 {\n  padding-top: 100px;\n  padding-bottom: 100px;\n  background-color: rgb(251, 247, 239);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_333853394\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large align-middle\"  id=\"row-1177236609\">\n\n\t<div id=\"col-1897130656\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2294127926\" class=\"text\">\n\t\t\n<h2 style=\"font-size: 40px; line-height:55px;  \">Stay, ride, repeat \u2013 secure your room now.<\/h2>\n\t\t\n<style>\n#text-2294127926 {\n  color: rgb(255, 255, 255);\n}\n#text-2294127926 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1897130656 > .col-inner {\n  margin: 0px 0px -62px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-475210719\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a class=\"button white is-larger\" style=\"border-radius:4px;\">\n\t\t<span>Book a room<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-475210719 > .col-inner {\n  margin: 0px 0px -51px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_333853394 {\n  padding-top: 100px;\n  padding-bottom: 100px;\n  background-color: #8b0414;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":453,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"footnotes":""},"class_list":["post-520","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages\/520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/comments?post=520"}],"version-history":[{"count":3,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages\/520\/revisions"}],"predecessor-version":[{"id":523,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages\/520\/revisions\/523"}],"up":[{"embeddable":true,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages\/453"}],"wp:attachment":[{"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/media?parent=520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}