{"id":504,"date":"2025-12-04T07:40:38","date_gmt":"2025-12-04T07:40:38","guid":{"rendered":"https:\/\/bergidyll.sebazzo.com\/rooms\/double-room-with-shared-bathroom\/"},"modified":"2025-12-10T23:36:17","modified_gmt":"2025-12-10T23:36:17","slug":"double-room-with-shared-bathroom","status":"publish","type":"page","link":"https:\/\/bergidyll.sebazzo.com\/en\/rooms\/double-room-with-shared-bathroom\/","title":{"rendered":"Double Room with Shared Bathroom"},"content":{"rendered":"\n\t<section class=\"section slider-landing\" id=\"section_270006696\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-262536643\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1450543132\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-1734597908\" class=\"text\">\n\t\t\n<h1 style=\"font-size: 60px;\">Double Room with Shared Bathroom <\/h1>\n\t\t\n<style>\n#text-1734597908 {\n  color: rgb(40, 40, 40);\n}\n#text-1734597908 > * {\n  color: rgb(40, 40, 40);\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1450543132 {\n  width: 60%;\n}\n#text-box-1450543132 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-262536643 {\n  padding-top: 318px;\n  background-color: rgb(247, 239, 222);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_270006696 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_270006696 .section-bg-overlay {\n  background-color: rgba(61, 36, 36, 0.5);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1679248386\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-59185320\">\n\n\t<div id=\"col-733710631\" class=\"col medium-5 small-12 large-5\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2094701102\" class=\"text\">\n\t\t\n<p style=\"font-size: 20px;  \">Bergidyll Andermatt.<\/p>\n<h2 style=\"font-size: 50px; line-height:55px; margin-top: -20px;\">Keep it simple. Share the vibe.<\/h2>\n\t\t\n<style>\n#text-2094701102 {\n  color: rgb(0, 0, 0);\n}\n#text-2094701102 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1208879705\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2526053240\" class=\"text\">\n\t\t\n<p style=\"font-size: 25px;\">Ideal for friends or uncomplicated travelers. Modern, cozy, and with a shared bathroom \u2013 perfect for those who prefer experiencing the outdoors to waiting indoors.<\/p>\n\t\t\n<style>\n#text-2526053240 {\n  color: rgb(0,0,0);\n}\n#text-2526053240 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1679248386 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(247, 239, 222);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_829761270\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large align-middle\"  id=\"row-1725269561\">\n\n\t<div id=\"col-736954228\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p style=\"font-size: 40px;  \">Amenities.<\/p>\n\n<div style=\"color:#000000; font-family:Arial, sans-serif; letter-spacing:2px; font-size:18px; line-height:1.6; width:100%;\">\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n 15\u201317 M\u00b2 \u2013 CLASSIC ALPINE, SIMPLE AND STRAIGHTFORWARD\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n SHARED BATHROOM WITH SHOWER\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n CARPETED FLOOR\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n TV-FREE\n    <\/div>\n<div style=\"border-bottom:1px solid #000000; padding:12px 0; font-weight:bold; width:100%;\">\n WLAN\n    <\/div>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-872361040\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"slider-wrapper relative\" id=\"slider-729673072\" >\n    <div class=\"slider slider-nav-dots-dashes-spaced slider-nav-circle slider-nav-large slider-nav-dark slider-style-normal slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": false,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_956679759\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/5483990c-3cbe-4481-93ae-b0e000cfe4ca-1024x576.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/5483990c-3cbe-4481-93ae-b0e000cfe4ca-1024x576.jpeg 1024w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/5483990c-3cbe-4481-93ae-b0e000cfe4ca-300x169.jpeg 300w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/5483990c-3cbe-4481-93ae-b0e000cfe4ca-768x432.jpeg 768w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/5483990c-3cbe-4481-93ae-b0e000cfe4ca-1536x864.jpeg 1536w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/5483990c-3cbe-4481-93ae-b0e000cfe4ca.jpeg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_956679759 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2009405889\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/077e718c-bb3b-4ab4-b414-b0e000cffdf2-1024x576.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/077e718c-bb3b-4ab4-b414-b0e000cffdf2-1024x576.jpeg 1024w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/077e718c-bb3b-4ab4-b414-b0e000cffdf2-300x169.jpeg 300w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/077e718c-bb3b-4ab4-b414-b0e000cffdf2-768x432.jpeg 768w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/077e718c-bb3b-4ab4-b414-b0e000cffdf2-1536x864.jpeg 1536w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/077e718c-bb3b-4ab4-b414-b0e000cffdf2.jpeg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2009405889 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_319824655\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/82a04ec1-0d90-4b49-b191-b0e000d02f31-1024x576.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/82a04ec1-0d90-4b49-b191-b0e000d02f31-1024x576.jpeg 1024w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/82a04ec1-0d90-4b49-b191-b0e000d02f31-300x169.jpeg 300w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/82a04ec1-0d90-4b49-b191-b0e000d02f31-768x432.jpeg 768w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/82a04ec1-0d90-4b49-b191-b0e000d02f31-1536x864.jpeg 1536w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/82a04ec1-0d90-4b49-b191-b0e000d02f31.jpeg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_319824655 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_39946996\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/aa8c6b1c-3071-4c94-8610-b0e000c2a64c-1024x576.jpeg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/aa8c6b1c-3071-4c94-8610-b0e000c2a64c-1024x576.jpeg 1024w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/aa8c6b1c-3071-4c94-8610-b0e000c2a64c-300x169.jpeg 300w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/aa8c6b1c-3071-4c94-8610-b0e000c2a64c-768x432.jpeg 768w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/aa8c6b1c-3071-4c94-8610-b0e000c2a64c-1536x864.jpeg 1536w, https:\/\/bergidyll.sebazzo.com\/wp-content\/uploads\/2025\/12\/aa8c6b1c-3071-4c94-8610-b0e000c2a64c.jpeg 1920w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_39946996 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-872361040 > .col-inner {\n  margin: 0px 0px -29px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_829761270 {\n  padding-top: 100px;\n  padding-bottom: 100px;\n  background-color: rgb(251, 247, 239);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1599160884\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row row-large align-middle\"  id=\"row-1878558711\">\n\n\t<div id=\"col-737746717\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-297502326\" class=\"text\">\n\t\t\n<h2 style=\"font-size: 40px; line-height:55px;  \">Stay, ride, repeat \u2013 secure your room now.<\/h2>\n\t\t\n<style>\n#text-297502326 {\n  color: rgb(255, 255, 255);\n}\n#text-297502326 > * {\n  color: rgb(255, 255, 255);\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-737746717 > .col-inner {\n  margin: 0px 0px -62px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-563479463\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a class=\"button white is-larger\" style=\"border-radius:4px;\">\n\t\t<span>Book a room<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\"><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-563479463 > .col-inner {\n  margin: 0px 0px -51px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1599160884 {\n  padding-top: 100px;\n  padding-bottom: 100px;\n  background-color: #8b0414;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":453,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-transparent-header.php","meta":{"footnotes":""},"class_list":["post-504","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages\/504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/comments?post=504"}],"version-history":[{"count":3,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages\/504\/revisions"}],"predecessor-version":[{"id":507,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages\/504\/revisions\/507"}],"up":[{"embeddable":true,"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/pages\/453"}],"wp:attachment":[{"href":"https:\/\/bergidyll.sebazzo.com\/en\/wp-json\/wp\/v2\/media?parent=504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}